{"id":330,"date":"2022-04-05T08:08:44","date_gmt":"2022-04-05T08:08:44","guid":{"rendered":"http:\/\/davidwrightyinc.com\/index.php\/contact\/"},"modified":"2023-09-15T13:59:40","modified_gmt":"2023-09-15T05:59:40","slug":"contact","status":"publish","type":"page","link":"http:\/\/davidwrightyinc.com\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-50752948 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-72c07434\"><h1 class=\"uagb-heading-text\">Get In Touch<\/h1><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c7ab7d66 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-ee26fd52\"><div class=\"wpforms-container wpforms-block wpforms-block-b5f97baa-4b92-4195-8e12-6836ee56b9d9\" id=\"wpforms-382\"><form id=\"wpforms-form-382\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"382\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/330\" data-token=\"a383ddbc9be5ab6ebed0f6f94471d23e\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-382-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-382-field_1\">Name<\/label><input type=\"text\" id=\"wpforms-382-field_1\" class=\"wpforms-field-large\" name=\"wpforms[fields][1]\" placeholder=\"Name\" ><\/div><div id=\"wpforms-382-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-382-field_2\">Email<\/label><input type=\"text\" id=\"wpforms-382-field_2\" class=\"wpforms-field-large\" name=\"wpforms[fields][2]\" placeholder=\"Email\" ><\/div><div id=\"wpforms-382-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-382-field_3\">Subject<\/label><input type=\"text\" id=\"wpforms-382-field_3\" class=\"wpforms-field-large\" name=\"wpforms[fields][3]\" placeholder=\"Subject\" ><\/div><div id=\"wpforms-382-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-382-field_4\">Message<\/label><textarea id=\"wpforms-382-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" placeholder=\"Message\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"382\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-382\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"SUBMIT\" aria-live=\"assertive\" value=\"wpforms-submit\">SUBMIT<\/button><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/davidwrightyinc.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9767742a alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-da8861b6\"><h2 class=\"uagb-heading-text\">Connect With Us<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-635914be alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-22e7c268\">\n<div class=\"wp-block-uagb-info-box uagb-block-a47b5d6b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M168.3 499.2C116.1 435 0 279.4 0 192C0 85.96 85.96 0 192 0C298 0 384 85.96 384 192C384 279.4 267 435 215.7 499.2C203.4 514.5 180.6 514.5 168.3 499.2H168.3zM192 256C227.3 256 256 227.3 256 192C256 156.7 227.3 128 192 128C156.7 128 128 156.7 128 192C128 227.3 156.7 256 192 256z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Address<\/h4><\/div><p class=\"uagb-ifb-desc\">3671 Sampson Street,Denver,Colorado<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5e0d0113\">\n<div class=\"wp-block-uagb-info-box uagb-block-e0412047 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M511.2 387l-23.25 100.8c-3.266 14.25-15.79 24.22-30.46 24.22C205.2 512 0 306.8 0 54.5c0-14.66 9.969-27.2 24.22-30.45l100.8-23.25C139.7-2.602 154.7 5.018 160.8 18.92l46.52 108.5c5.438 12.78 1.77 27.67-8.98 36.45L144.5 207.1c33.98 69.22 90.26 125.5 159.5 159.5l44.08-53.8c8.688-10.78 23.69-14.51 36.47-8.975l108.5 46.51C506.1 357.2 514.6 372.4 511.2 387z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Call Us<\/h4><\/div><p class=\"uagb-ifb-desc\">303-875-7479<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-14cb4502\">\n<div class=\"wp-block-uagb-info-box uagb-block-b5feeae4 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M464 64C490.5 64 512 85.49 512 112C512 127.1 504.9 141.3 492.8 150.4L275.2 313.6C263.8 322.1 248.2 322.1 236.8 313.6L19.2 150.4C7.113 141.3 0 127.1 0 112C0 85.49 21.49 64 48 64H464zM217.6 339.2C240.4 356.3 271.6 356.3 294.4 339.2L512 176V384C512 419.3 483.3 448 448 448H64C28.65 448 0 419.3 0 384V176L217.6 339.2z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Email<\/h4><\/div><p class=\"uagb-ifb-desc\">David@davidwrightyinc.com<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11997878\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b44b50f3\"><h4 class=\"uagb-heading-text\">Follow Us<\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share uagb-social-share__outer-wrap uagb-social-share__layout-horizontal uagb-block-fbed77eb\">\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-807c04ad\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.facebook.com\/sharer.php?u=\" tabindex=\"0\" role=\"button\" aria-label=\"facebook\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.8 90.69 226.4 209.3 245V327.7h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.3 482.4 504 379.8 504 256z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-09572a50\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/twitter.com\/share?url=\" tabindex=\"0\" role=\"button\" aria-label=\"twitter\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zm-48.9 158.8c.2 2.8 .2 5.7 .2 8.5 0 86.7-66 186.6-186.6 186.6-37.2 0-71.7-10.8-100.7-29.4 5.3 .6 10.4 .8 15.8 .8 30.7 0 58.9-10.4 81.4-28-28.8-.6-53-19.5-61.3-45.5 10.1 1.5 19.2 1.5 29.6-1.2-30-6.1-52.5-32.5-52.5-64.4v-.8c8.7 4.9 18.9 7.9 29.6 8.3a65.45 65.45 0 0 1 -29.2-54.6c0-12.2 3.2-23.4 8.9-33.1 32.3 39.8 80.8 65.8 135.2 68.6-9.3-44.5 24-80.6 64-80.6 18.9 0 35.9 7.9 47.9 20.7 14.8-2.8 29-8.3 41.6-15.8-4.9 15.2-15.2 28-28.8 36.1 13.2-1.4 26-5.1 37.8-10.2-8.9 13.1-20.1 24.7-32.9 34z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-7528fbaf\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/pinterest.com\/pin\/create\/link\/?url=\" tabindex=\"0\" role=\"button\" aria-label=\"pinterest\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M448 80v352c0 26.5-21.5 48-48 48H154.4c9.8-16.4 22.4-40 27.4-59.3 3-11.5 15.3-58.4 15.3-58.4 8 15.3 31.4 28.2 56.3 28.2 74.1 0 127.4-68.1 127.4-152.7 0-81.1-66.2-141.8-151.4-141.8-106 0-162.2 71.1-162.2 148.6 0 36 19.2 80.8 49.8 95.1 4.7 2.2 7.1 1.2 8.2-3.3 .8-3.4 5-20.1 6.8-27.8 .6-2.5 .3-4.6-1.7-7-10.1-12.3-18.3-34.9-18.3-56 0-54.2 41-106.6 110.9-106.6 60.3 0 102.6 41.1 102.6 99.9 0 66.4-33.5 112.4-77.2 112.4-24.1 0-42.1-19.9-36.4-44.4 6.9-29.2 20.3-60.7 20.3-81.8 0-53-75.5-45.7-75.5 25 0 21.7 7.3 36.5 7.3 36.5-31.4 132.8-36.1 134.5-29.6 192.6l2.2 .8H48c-26.5 0-48-21.5-48-48V80c0-26.5 21.5-48 48-48h352c26.5 0 48 21.5 48 48z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ce55a577 alignfull uagb-is-root-container\">\t\t\t<div \n\t\t\tclass=\"wp-block-uagb-google-map uagb-google-map__wrap uagb-block-cbe0fc4c    \"\n\t\t\tstyle=\"\" >\n\t\t\t\t<iframe\n\t\t\t\t\tclass=\"uagb-google-map__iframe\"\n\t\t\t\t\ttitle=\"Google Map for \"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=3671%20Sampson%20Street%2CDenver%2CColorado&#038;z=17&#038;hl=en&#038;t=m&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\twidth=\"640\"\n\t\t\t\t\theight=\"500\"\n\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t><\/iframe>\n\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Get In Touch Connect With Us Follow Us<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"plain-container","ast-site-content-layout":"normal-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"class_list":["post-330","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"admin","author_link":"http:\/\/davidwrightyinc.com\/index.php\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Get In Touch Connect With Us Follow Us","_links":{"self":[{"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/pages\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":5,"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/pages\/330\/revisions"}],"predecessor-version":[{"id":1139,"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/pages\/330\/revisions\/1139"}],"wp:attachment":[{"href":"http:\/\/davidwrightyinc.com\/index.php\/wp-json\/wp\/v2\/media?parent=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}